{"id":8100,"date":"2023-11-06T21:07:46","date_gmt":"2023-11-06T21:07:46","guid":{"rendered":"https:\/\/radioprincesa2010.com.br\/fm\/?p=8100"},"modified":"2023-11-06T21:07:52","modified_gmt":"2023-11-06T21:07:52","slug":"grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado","status":"publish","type":"post","link":"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/","title":{"rendered":"Grande evento reuniu a banda municipal de Selbach e a ONG Filhos do Cora\u00e7\u00e3o de Ibirub\u00e1 no espet\u00e1culo musical na Casa da Cultura no\u00a0\u00faltimo\u00a0s\u00e1bado"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n<div class=\"wp-block-envira-envira-gallery\"><div id=\"envira-gallery-wrap-8118\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div style=\"opacity: 0.0\"  data-row-height=\"150\" data-gallery-theme=\"normal\" id=\"envira-gallery-8118\" class=\"envira-gallery-public envira-gallery-justified-public envira-gallery-0-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"0\"><div id=\"envira-gallery-item-8116\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0016.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0016\" data-envira-caption=\"IMG-20231106-WA0016\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8116\" class=\"envira-gallery-image envira-gallery-image-1 envira-normal envira-lazy\" data-envira-index=\"1\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0016-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0016-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8116\" data-envira-caption=\"IMG-20231106-WA0016\" alt=\"\" title=\"IMG-20231106-WA0016\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0016-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0016-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8115\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0015.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0015\" data-envira-caption=\"IMG-20231106-WA0015\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8115\" class=\"envira-gallery-image envira-gallery-image-2 envira-normal envira-lazy\" data-envira-index=\"2\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0015-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0015-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8115\" data-envira-caption=\"IMG-20231106-WA0015\" alt=\"\" title=\"IMG-20231106-WA0015\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0015-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0015-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8114\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0014.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0014\" data-envira-caption=\"IMG-20231106-WA0014\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8114\" class=\"envira-gallery-image envira-gallery-image-3 envira-normal envira-lazy\" data-envira-index=\"3\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0014-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0014-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8114\" data-envira-caption=\"IMG-20231106-WA0014\" alt=\"\" title=\"IMG-20231106-WA0014\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0014-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0014-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8113\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0013.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0013\" data-envira-caption=\"IMG-20231106-WA0013\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8113\" class=\"envira-gallery-image envira-gallery-image-4 envira-normal envira-lazy\" data-envira-index=\"4\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0013-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0013-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8113\" data-envira-caption=\"IMG-20231106-WA0013\" alt=\"\" title=\"IMG-20231106-WA0013\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0013-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0013-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8112\" class=\"envira-gallery-item enviratope-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0012.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0012\" data-envira-caption=\"IMG-20231106-WA0012\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8112\" class=\"envira-gallery-image envira-gallery-image-5 envira-normal envira-lazy\" data-envira-index=\"5\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0012-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0012-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8112\" data-envira-caption=\"IMG-20231106-WA0012\" alt=\"\" title=\"IMG-20231106-WA0012\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0012-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0012-640x480.jpg 2x\" data-envira-width=\"150\" data-envira-height=\"150\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8111\" class=\"envira-gallery-item enviratope-item envira-gallery-item-6 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0011.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0011\" data-envira-caption=\"IMG-20231106-WA0011\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8111\" class=\"envira-gallery-image envira-gallery-image-6 envira-normal envira-lazy\" data-envira-index=\"6\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0011-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0011-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8111\" data-envira-caption=\"IMG-20231106-WA0011\" alt=\"\" title=\"IMG-20231106-WA0011\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0011-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0011-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8110\" class=\"envira-gallery-item enviratope-item envira-gallery-item-7 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0010.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0010\" data-envira-caption=\"IMG-20231106-WA0010\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8110\" class=\"envira-gallery-image envira-gallery-image-7 envira-normal envira-lazy\" data-envira-index=\"7\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0010-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0010-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8110\" data-envira-caption=\"IMG-20231106-WA0010\" alt=\"\" title=\"IMG-20231106-WA0010\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0010-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0010-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8109\" class=\"envira-gallery-item enviratope-item envira-gallery-item-8 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0009.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0009\" data-envira-caption=\"IMG-20231106-WA0009\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8109\" class=\"envira-gallery-image envira-gallery-image-8 envira-normal envira-lazy\" data-envira-index=\"8\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0009-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0009-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8109\" data-envira-caption=\"IMG-20231106-WA0009\" alt=\"\" title=\"IMG-20231106-WA0009\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0009-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0009-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8108\" class=\"envira-gallery-item enviratope-item envira-gallery-item-9 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0008.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0008\" data-envira-caption=\"IMG-20231106-WA0008\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8108\" class=\"envira-gallery-image envira-gallery-image-9 envira-normal envira-lazy\" data-envira-index=\"9\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0008-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0008-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8108\" data-envira-caption=\"IMG-20231106-WA0008\" alt=\"\" title=\"IMG-20231106-WA0008\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0008-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0008-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8107\" class=\"envira-gallery-item enviratope-item envira-gallery-item-10 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0007.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0007\" data-envira-caption=\"IMG-20231106-WA0007\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8107\" class=\"envira-gallery-image envira-gallery-image-10 envira-normal envira-lazy\" data-envira-index=\"10\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0007-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0007-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8107\" data-envira-caption=\"IMG-20231106-WA0007\" alt=\"\" title=\"IMG-20231106-WA0007\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0007-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0007-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8106\" class=\"envira-gallery-item enviratope-item envira-gallery-item-11 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0006.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0006\" data-envira-caption=\"IMG-20231106-WA0006\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8106\" class=\"envira-gallery-image envira-gallery-image-11 envira-normal envira-lazy\" data-envira-index=\"11\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0006-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0006-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8106\" data-envira-caption=\"IMG-20231106-WA0006\" alt=\"\" title=\"IMG-20231106-WA0006\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0006-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0006-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8105\" class=\"envira-gallery-item enviratope-item envira-gallery-item-12 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0005.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0005\" data-envira-caption=\"IMG-20231106-WA0005\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8105\" class=\"envira-gallery-image envira-gallery-image-12 envira-normal envira-lazy\" data-envira-index=\"12\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0005-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0005-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8105\" data-envira-caption=\"IMG-20231106-WA0005\" alt=\"\" title=\"IMG-20231106-WA0005\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0005-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0005-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8104\" class=\"envira-gallery-item enviratope-item envira-gallery-item-13 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0004.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0004\" data-envira-caption=\"IMG-20231106-WA0004\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8104\" class=\"envira-gallery-image envira-gallery-image-13 envira-normal envira-lazy\" data-envira-index=\"13\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0004-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0004-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8104\" data-envira-caption=\"IMG-20231106-WA0004\" alt=\"\" title=\"IMG-20231106-WA0004\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0004-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0004-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8103\" class=\"envira-gallery-item enviratope-item envira-gallery-item-14 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0003.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0003\" data-envira-caption=\"IMG-20231106-WA0003\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8103\" class=\"envira-gallery-image envira-gallery-image-14 envira-normal envira-lazy\" data-envira-index=\"14\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0003-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0003-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8103\" data-envira-caption=\"IMG-20231106-WA0003\" alt=\"\" title=\"IMG-20231106-WA0003\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0003-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0003-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8102\" class=\"envira-gallery-item enviratope-item envira-gallery-item-15 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0002.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0002\" data-envira-caption=\"IMG-20231106-WA0002\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8102\" class=\"envira-gallery-image envira-gallery-image-15 envira-normal envira-lazy\" data-envira-index=\"15\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0002-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0002-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8102\" data-envira-caption=\"IMG-20231106-WA0002\" alt=\"\" title=\"IMG-20231106-WA0002\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0002-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0002-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-8101\" class=\"envira-gallery-item enviratope-item envira-gallery-item-16 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001.jpg\" class=\"envira-gallery-8118 envira-gallery-link\" rel=\"enviragallery8118\" title=\"IMG-20231106-WA0001\" data-envira-caption=\"IMG-20231106-WA0001\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-8101\" class=\"envira-gallery-image envira-gallery-image-16 envira-normal envira-lazy\" data-envira-index=\"16\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1024x682-640x480.jpg\" data-envira-src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1024x682-640x480.jpg\" data-envira-gallery-id=\"8118\" data-envira-item-id=\"8101\" data-envira-caption=\"IMG-20231106-WA0001\" alt=\"\" title=\"IMG-20231106-WA0001\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1024x682-640x480.jpg 400w,https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1024x682-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0016.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0015.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0014.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0013.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0012.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0011.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0010.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0009.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0008.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0007.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0006.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0005.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0004.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0003.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0002.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001.jpg\" alt=\"\" \/><\/noscript><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">TALVEZ TAMB\u00c9M INTERESSE. Tenha paci\u00eancia e aguarde os link e v\u00eddeos carregarem \ud83d\ude42<\/h2>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-11450 post type-post status-publish format-standard has-post-thumbnail hentry category-geral\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/ajude-a-maria-antonia\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/x1.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Ajude a Maria Ant\u00f4nia\" style=\"object-fit:cover;\" srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/x1.jpeg 1080w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/x1-240x300.jpeg 240w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/x1-819x1024.jpeg 819w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/x1-768x960.jpeg 768w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/x1-48x60.jpeg 48w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title\"><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/ajude-a-maria-antonia\/\" target=\"_self\" >Ajude a Maria Ant\u00f4nia<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-11446 post type-post status-publish format-standard has-post-thumbnail hentry category-geral\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/decima-primeira-rodada-do-campeonato-cresol-de-futsal-2a-divisao\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/500-6.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"D\u00e9cima primeira Rodada do Campeonato Cresol de Futsal 2\u00aa Divis\u00e3o\" style=\"object-fit:cover;\" srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/500-6.jpg 500w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/500-6-300x184.jpg 300w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/500-6-98x60.jpg 98w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title\"><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/decima-primeira-rodada-do-campeonato-cresol-de-futsal-2a-divisao\/\" target=\"_self\" >D\u00e9cima primeira Rodada do Campeonato Cresol de Futsal 2\u00aa Divis\u00e3o<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-11435 post type-post status-publish format-standard has-post-thumbnail hentry category-geral\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/ampliacao-de-horarios-da-saude-em-selbach\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/3.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Amplia\u00e7\u00e3o de Hor\u00e1rios da Sa\u00fade em Selbach\" style=\"object-fit:cover;\" srcset=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/3.jpeg 500w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/3-300x300.jpeg 300w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/3-150x150.jpeg 150w, https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2026\/05\/3-60x60.jpeg 60w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title\"><a href=\"https:\/\/radioprincesa2010.com.br\/fm\/ampliacao-de-horarios-da-saude-em-selbach\/\" target=\"_self\" >Amplia\u00e7\u00e3o de Hor\u00e1rios da Sa\u00fade em Selbach<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><\/ul><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Bail\u00e3o em Bela Vista &#8211; Se inscreva no canal!<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#BAILE de #CHOPP em cidade Pequena - Bela Vista Selbach\" width=\"925\" height=\"520\" src=\"https:\/\/www.youtube.com\/embed\/Uv2y8bYFJQE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/youtu.be\/Uv2y8bYFJQE\" target=\"_blank\" rel=\"noreferrer noopener\">ou veja aqui<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">CONFIRA NOSSA HOMENAGEM A XV BLUMENFEST:<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Como \u00e9 uma festa de #ALEM\u00c3O em cidade pequena - Selbach RS\" width=\"925\" height=\"520\" src=\"https:\/\/www.youtube.com\/embed\/okokN0UxJpc?start=16&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.youtube.com\/watch?v=okokN0UxJpc&amp;t=16s\" target=\"_blank\" rel=\"noreferrer noopener\">ou veja aqui<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Gosta de corrida de rua?<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"T\u00eanis caro melhora a performance na corrida? ASICS NIMBUS 25\" width=\"925\" height=\"520\" src=\"https:\/\/www.youtube.com\/embed\/opBoo3UzFrg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/youtu.be\/opBoo3UzFrg\" target=\"_blank\" rel=\"noreferrer noopener\">ou veja aqui<\/a><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TALVEZ TAMB\u00c9M INTERESSE. Tenha paci\u00eancia e aguarde os link e v\u00eddeos carregarem \ud83d\ude42 Bail\u00e3o em Bela Vista &#8211; Se inscreva no canal! CONFIRA NOSSA HOMENAGEM A XV BLUMENFEST: Gosta de corrida de rua?<\/p>\n","protected":false},"author":1,"featured_media":8117,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[286,598,8],"class_list":["post-8100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-banda-municipal","tag-ong-filhos-do-coracao","tag-selbach"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grande evento reuniu a banda municipal de Selbach e a ONG Filhos do Cora\u00e7\u00e3o de Ibirub\u00e1 no espet\u00e1culo musical na Casa da Cultura no\u00a0\u00faltimo\u00a0s\u00e1bado - R\u00e1dio Princesa FM 104.9 Mhz<\/title>\n<link rel=\"canonical\" href=\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grande evento reuniu a banda municipal de Selbach e a ONG Filhos do Cora\u00e7\u00e3o de Ibirub\u00e1 no espet\u00e1culo musical na Casa da Cultura no\u00a0\u00faltimo\u00a0s\u00e1bado - R\u00e1dio Princesa FM 104.9 Mhz\" \/>\n<meta property=\"og:description\" content=\"TALVEZ TAMB\u00c9M INTERESSE. Tenha paci\u00eancia e aguarde os link e v\u00eddeos carregarem \ud83d\ude42 Bail\u00e3o em Bela Vista &#8211; Se inscreva no canal! CONFIRA NOSSA HOMENAGEM A XV BLUMENFEST: Gosta de corrida de rua?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Princesa FM 104.9 Mhz\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-06T21:07:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T21:07:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\">\n\t<meta name=\"twitter:data1\" content=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/#website\",\"url\":\"https:\/\/radioprincesa2010.com.br\/fm\/\",\"name\":\"R\\u00e1dio Princesa FM 104.9 Mhz\",\"description\":\"Com voc\\u00ea o tempo todo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/radioprincesa2010.com.br\/fm\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1.jpg\",\"contentUrl\":\"https:\/\/radioprincesa2010.com.br\/fm\/wp-content\/uploads\/2023\/11\/IMG-20231106-WA0001-1.jpg\",\"width\":500,\"height\":333},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/#webpage\",\"url\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/\",\"name\":\"Grande evento reuniu a banda municipal de Selbach e a ONG Filhos do Cora\\u00e7\\u00e3o de Ibirub\\u00e1 no espet\\u00e1culo musical na Casa da Cultura no\\u00a0\\u00faltimo\\u00a0s\\u00e1bado - R\\u00e1dio Princesa FM 104.9 Mhz\",\"isPartOf\":{\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/#primaryimage\"},\"datePublished\":\"2023-11-06T21:07:46+00:00\",\"dateModified\":\"2023-11-06T21:07:52+00:00\",\"author\":{\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/#\/schema\/person\/7387850c16b3f47de42a1accfc7045c8\"},\"breadcrumb\":{\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/\",\"url\":\"https:\/\/radioprincesa2010.com.br\/fm\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/\",\"url\":\"https:\/\/radioprincesa2010.com.br\/fm\/grande-evento-reuniu-a-banda-municipal-de-selbach-e-a-ong-filhos-do-coracao-de-ibiruba-no-espetaculo-musical-na-casa-da-cultura-no-ultimo-sabado\/\",\"name\":\"Grande evento reuniu a banda municipal de Selbach e a ONG Filhos do Cora\\u00e7\\u00e3o de Ibirub\\u00e1 no espet\\u00e1culo musical na Casa da Cultura no\\u00a0\\u00faltimo\\u00a0s\\u00e1bado\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/#\/schema\/person\/7387850c16b3f47de42a1accfc7045c8\",\"name\":\"Princesa ADM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/radioprincesa2010.com.br\/fm\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f30936cf78b511d12d0dda9d77461df5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f30936cf78b511d12d0dda9d77461df5?s=96&d=mm&r=g\",\"caption\":\"Princesa ADM\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/posts\/8100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/comments?post=8100"}],"version-history":[{"count":2,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/posts\/8100\/revisions"}],"predecessor-version":[{"id":8122,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/posts\/8100\/revisions\/8122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/media\/8117"}],"wp:attachment":[{"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/media?parent=8100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/categories?post=8100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioprincesa2010.com.br\/fm\/wp-json\/wp\/v2\/tags?post=8100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}